{"id":1052,"date":"2009-06-21T20:54:25","date_gmt":"2009-06-21T18:54:25","guid":{"rendered":"http:\/\/www.mkb-rechtsanwaelte.de\/test\/wordpress\/?p=22"},"modified":"2009-06-21T20:54:25","modified_gmt":"2009-06-21T18:54:25","slug":"version-0-15","status":"publish","type":"post","link":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/version-0-15\/","title":{"rendered":"Version 0.15"},"content":{"rendered":"<p>2. Tag der Installation meines Blogs.<\/p>\n<p>Nachdem ich nun die weiteren M\u00f6glichkeiten von WordPress erkundet habe, angefanden von Widgets \u00fcber Themes bis hin zur multimedialen Einbindung von Videos und anderen Schmankerln, bin ich kaum noch in der Lage juristische Inhalte\u00a0 zu verbreiten, man muss ja alles ausprobieren. Aber es verk\u00fcrzt nat\u00fcrlich auch die Strecke bis zur &#8222;Release&#8220;-F\u00e4higkeit des Blogs.<\/p>\n<p>Es kann nicht mehr lange dauern !!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2. Tag der Installation meines Blogs. Nachdem ich nun die weiteren M\u00f6glichkeiten von WordPress erkundet habe, angefanden von Widgets \u00fcber Themes bis hin zur multimedialen Einbindung von Videos und anderen Schmankerln, bin ich kaum noch in der Lage juristische Inhalte\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[692],"_links":{"self":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/1052"}],"collection":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/comments?post=1052"}],"version-history":[{"count":0,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/1052\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/media?parent=1052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/categories?post=1052"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/tags?post=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}