{"id":178,"date":"2009-12-02T23:09:39","date_gmt":"2009-12-02T21:09:39","guid":{"rendered":"http:\/\/www.mkb-rechtsanwaelte.de\/test\/wordpress\/?p=178"},"modified":"2009-12-02T23:09:39","modified_gmt":"2009-12-02T21:09:39","slug":"update-der-drohanruf-k-o-durch-das-gericht","status":"publish","type":"post","link":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/update-der-drohanruf-k-o-durch-das-gericht\/","title":{"rendered":"Update &#8211; Der Drohanruf &#8211; K.O. durch das Gericht"},"content":{"rendered":"<p><a title=\"Der Drohanruf\" href=\"http:\/\/www.mkb-rechtsanwaelte.de\/test\/wordpress\/?p=161#more-161\" target=\"_blank\">Hier<\/a> hatte ich bereits \u00fcber ein Verfahren berichtet, in dem es um die Verj\u00e4hrung von R\u00fcckbauanspr\u00fcchen und die fehlende Aufrechnungsm\u00f6glichkeit gem\u00e4\u00df <a title=\"Aufrechnung von verj\u00e4hrten Forderungen\" href=\"http:\/\/gesetze.juris.de\/bgb\/__215.html\" target=\"_blank\">\u00a7 215 BGB<\/a> bei Stellung einer Bankb\u00fcrgschaft geht. Die Gegenseite hat nun Klage eingereicht. Das Gericht hat vorab ebenfalls seinen Senf zu der Klage abgegeben:<\/p>\n<p><!--more-->Bevor ich \u00fcberhaupt meine Klageerwiderung abgeben konnte &#8211; ich habe mich lediglich bei Gericht legitimiert &#8211; hat das Gericht mit der Zustellung bereits darauf hingewiesen dass die Klage bisher unschl\u00fcssig ist und kurzfristig Termin zur m\u00fcndlichen Verhandlung angesetzt. Aus dem Juristischen ins Deutsche \u00fcbersetzt bedeutet dies: &#8222;Junge, nimm die Klage lieber schnell\u00a0 zur\u00fcck, bei uns wird das nichts mehr&#8220;.\u00a0 Denn normalerweise wird erst einmal die Klageerwiderung abgewartet bis ein Hinweis ergeht oder ein Termin zur m\u00fcndlichen Verhandlung festgelegt wird. Ohne Kenntnis der Klageerwiderung kann dies nur mit einer beabsichtigten Klageabweisung \u00fcbersetzt werden. Schnell verdientes Geld. Wie lautete gestern die \u00dcberschrift bei Richter Ballmann: &#8222;<a title=\"Im Namen des Volkers\" href=\"http:\/\/richter-ballmann.info\/2009\/12\/01\/manche-parteien-sollten-vor-ihrem-anwalt-geschuetzt-werden\/\" target=\"_blank\">Manche Parteien sollten vor ihrem Anwalt gesch\u00fctzt werden<\/a>&#8222;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier hatte ich bereits \u00fcber ein Verfahren berichtet, in dem es um die Verj\u00e4hrung von R\u00fcckbauanspr\u00fcchen und die fehlende Aufrechnungsm\u00f6glichkeit gem\u00e4\u00df \u00a7 215 BGB bei Stellung einer Bankb\u00fcrgschaft geht. Die Gegenseite hat nun Klage eingereicht. Das Gericht hat vorab ebenfalls<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,700,9],"tags":[273,783,804,67,805,806,344,790],"_links":{"self":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/178"}],"collection":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/comments?post=178"}],"version-history":[{"count":0,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/178\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/media?parent=178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/categories?post=178"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/tags?post=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}