{"id":737,"date":"2009-11-25T23:39:56","date_gmt":"2009-11-25T21:39:56","guid":{"rendered":"http:\/\/mkb-rechtsanwaelte.de\/blog\/wordpress\/?p=93"},"modified":"2009-11-25T23:39:56","modified_gmt":"2009-11-25T21:39:56","slug":"das-dilemma-bei-der-filesharing-abmahnung","status":"publish","type":"post","link":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/das-dilemma-bei-der-filesharing-abmahnung\/","title":{"rendered":"Das Dilemma bei der Filesharing Abmahnung"},"content":{"rendered":"<p>Es ist Herbst, die Abende werden k\u00fchl und regnerischer, man sitzt vor dem PC. Es ist wieder &#8222;<a title=\"Halbjahresbilanz\" href=\"http:\/\/www.verein-gegen-den-abmahnwahn.de\/zentrale\/download\/pdf_dateien\/halbjahresbilanz%202009.pdf\" target=\"_blank\">Abmahnsaison<\/a>&#8222;,\u00a0 man erkennt es an der Zahl der neuen Filesharingabmahnungen. Der Abgemahnte &#8211; lassen wir es mal dahingestellt ob nun zu Unrecht oder zu Recht &#8211; steckt dabei immer in einer &#8211; von den Abmahnern durchaus so beabsichtigten, bl\u00f6den Situation:<\/p>\n<p><!--more-->Meist werden pauschale Summe f\u00fcr die Rechtsverletzung als &#8222;Vergleich&#8220; angeboten, meist ein Betrag zwischen 400 und 500,- \u20ac. Nimmt er diesen Vergleich nicht an, werden mit Anwalts- Gerichtskosten und Schadensersatz weit \u00fcber 1000,- \u20ac gedroht. Geht der Abgemahnte zum Anwalt, will dieser &#8211; verst\u00e4ndlicherweise &#8211; auch bezahlt werden. Dabei wird selten eine Summe unter 200,- \u20ac rauskommen, meist eher mehr, und wenn der Anwalt nach RVG abrechnet\u00a0 sogar die gleiche Summe, die die Abmahnkanzlei haben will. Das Ergebnis der anwaltlichen Beratung ist aber \u00e4u\u00dferst unterschiedlich. In manchen F\u00e4llen kann der gegnerische Anspruch abgewehrt werden, etwa weil dem Rechteinhaber auf Grund der Sachlage das Risiko eines Verfahrens zu gro\u00df ist.\u00a0 In anderen F\u00e4llen ist der Versto\u00df so eindeutig, dass dem Mandanten nur geraten werden kann, das Angebot der Gegenseite schnell und in entsprechend modifizierter Art und Weise\u00a0 anzunehmen. Oft wird mit der Gegenseite ein Vergleich ausgehandelt. Das kostet dann beim eigenen Anwalt &#8222;extra&#8220;.<\/p>\n<p>Der Mandant ist dann schnell ent\u00e4uscht, weil er nach seinem Denken in der Summe nur &#8222;draufgelegt&#8220; hat, da er neben einer Zahlung an den Gegner auch noch seinen eigenen Anwalt bezahlen muss (der in solchen F\u00e4llen meist Vorkasse nimmt oder nehmen sollte). Warum also sollte es sich lohnen eine Filesharing Abmahnung anwaltlich \u00fcberpr\u00fcfen zu lassen, wenn man im Zweifel nur drauflegt\u00a0 ? Es gibt im Internet ja genug &#8222;Rezepte&#8220; wie auf eine derartige Filesharin Abmahnung zu reagieren ist.<\/p>\n<p>Das Risiko einer solchen Vorgehensweise ist jedoch hoch:<\/p>\n<ul>\n<li>Nicht jede im Internet kursierende &#8222;modifizierte Unterlassungserkl\u00e4rung&#8220; gen\u00fcgt den Anforderung der Rechtsprechung an eine strafbewehrte Unterlassungserkl\u00e4rung. Die Gefahr, dass irgendwelche unwissenden Trolle hier zugeschlagen haben ist gro\u00df;<\/li>\n<li>Weiterhin sollte derjenige, der eine strafbewehrte Unterlassungserkl\u00e4rung abgibt, auch \u00fcber dessen Reichweite Bescheid wissen. Eine solche Verpflichtungserkl\u00e4rung hat eine G\u00fcltigkeit von 30 Jahren. Wer\u00a0 eine solche Erkl\u00e4rung unterschreibt und dann fr\u00f6hlich weiter &#8222;saugt&#8220; kommt schnell in die Gefahr die versprochene Vertragsstrafe (meist mehrere tausend Euro) zahlen zu m\u00fcssen;<\/li>\n<li> Oftmals sind die Abmahnmodelle durchaus fragw\u00fcrdig, insbesondere bei den einschl\u00e4gig bekannten Rechteinhabern. Hier kursieren im Internet durchaus <a title=\"Anschreiben Rechteinhaber\" href=\"http:\/\/88.80.16.63\/leak\/davenport-lyons-and-kornmeier-monetary-and-working-correspondence.pdf\" target=\"_blank\">Unterlagen<\/a> und andere <a title=\"Einsch\u00e4tzung der Kollegen Damm &amp; Partner\" href=\"http:\/\/www.damm-legal.de\/filesharing-sind-die-abmahnungen-im-namen-von-digiprotect-rechtsmissbraeuchlich-die-maer-vom-erfolgshonorar\" target=\"_blank\">Materialien<\/a>, die den Abmahner in einem Proze\u00df in Schwierigkeiten bringen. Nur der fachlich versierte Rechtsanwalt wird beurteilen k\u00f6nnen, inwieweit diese f\u00fcr das vorliegende Verfahren wertvoll sind;<\/li>\n<li>Der Anwalt kann auch Absch\u00e4tzen welche Verteidigungsstrategien sinnvoll sind und welche Einw\u00e4nde unbeachtlich sind; dem Mandanten wird erheblicher zeitlicher und administrativer Aufwand gespart;<\/li>\n<li>Der Anwalt kann auch vorbeugend beraten, um weitere, \u00e4hnlich gelagerte Abmahnungen zu vermeiden (wobei nicht unbedingt <a title=\"Kommentierung zum Abmahnschutzpaket\" href=\"http:\/\/www.damm-legal.de\/filesharing-der-wert-von-abmahnschutzpaketen-fuer-den-internetnutzer\" target=\"_blank\">diese Modelle<\/a> gemeint sind);<\/li>\n<\/ul>\n<p>Insgesamt ist daher aus objektiver Sicht auch trotz der eventuell h\u00f6heren Kosten einen anwaltliche Beratung unerl\u00e4sslich, denn es ist aus meiner Sicht f\u00fcr einen juristischen Laien fast unm\u00f6glich, die irrelevanten Informationen im Internet zum Thema &#8222;Filesharing Abmahnung&#8220; \u00a0 von den relevanten Informationen zu trennen. Wer &#8222;Rechtssicherheit&#8220; und Aufkl\u00e4rung \u00fcber die Risiken haben will, muss zum Anwalt gehen, auch wenn es vielleicht\u00a0 etwas &#8222;mehr&#8220; kostet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist Herbst, die Abende werden k\u00fchl und regnerischer, man sitzt vor dem PC. Es ist wieder &#8222;Abmahnsaison&#8222;,\u00a0 man erkennt es an der Zahl der neuen Filesharingabmahnungen. Der Abgemahnte &#8211; lassen wir es mal dahingestellt ob nun zu Unrecht oder<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[23,31],"tags":[80,81,82,83,75,84,85,86,87],"_links":{"self":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/737"}],"collection":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/comments?post=737"}],"version-history":[{"count":0,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/737\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/media?parent=737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/categories?post=737"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/tags?post=737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}