{"id":744,"date":"2010-02-05T11:56:12","date_gmt":"2010-02-05T09:56:12","guid":{"rendered":"http:\/\/mkb-rechtsanwaelte.de\/blog\/wordpress\/?p=127"},"modified":"2010-02-05T11:56:12","modified_gmt":"2010-02-05T09:56:12","slug":"update-der-anschlussinhaber-haftet-volltext-der-entscheidung-olg-koln-6-u-10109","status":"publish","type":"post","link":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/update-der-anschlussinhaber-haftet-volltext-der-entscheidung-olg-koln-6-u-10109\/","title":{"rendered":"Update: Der Anschlussinhaber haftet &#8211; Volltext der Entscheidung OLG K\u00f6ln 6 U 101\/09"},"content":{"rendered":"<p>Vor einigen Wochen hatte ich \u00fcber eine <a title=\"Beitrag vom 7.1.2010\" href=\"http:\/\/mkb-rechtsanwaelte.de\/blog\/wordpress\/?p=110\" target=\"_self\">Entscheidung des OLG K\u00f6ln berichtet<\/a>, die in der Presse zu einigen Schlagzeilen f\u00fchrte. Mittlerweile liegt der Volltext der Entscheidung zu dem <a title=\"Volltext via MIR\" href=\"http:\/\/medien-internet-und-recht.de\/pdf\/VT_MIR_2010_007.pdf\" target=\"_blank\">Urteil des OLG K\u00f6ln vom 23.12.2009, AZ 6 U 101\/09<\/a> vor (Vorinstanz: <a title=\"Urteil des LG K\u00f6ln vom 13.5.2009 \" href=\"http:\/\/www.justiz.nrw.de\/nrwe\/lgs\/koeln\/lg_koeln\/j2009\/28_O_889_08urteil20090513.html\" target=\"_blank\">LG K\u00f6ln, Urteil vom 13.5.2009 AZ: 28 O 889\/08<\/a>). Aus der Begr\u00fcndung kann man ersehen, dass sich das OLG ein wenig vor einer klaren Aussage zum Thema \u00dcberwachungspflichten gedr\u00fcckt hat:<\/p>\n<p><!--more--><\/p>\n<p style=\"padding-left: 30px;\">&#8222;Inwieweit der Inhaber eines Internetanschlusses daf\u00fcr Sorge zu tragen  hat, dass Dritte, die Zugang zu dem Internetanschluss haben, bei der  Nutzung dieses Internetanschlusses nicht urheberrechtliche  Nutzungsrechte verletzen, wird in der Rechtsprechung nicht einheitlich  beurteilt, (vgl. LG Hamburg, MMR 2006, 700; CR 2007, 121 f; OLG Hamburg  [Streitwertentscheidung] GRUR-RR 2007, 661 Rz 10; OLG Frankfurt GRUR-RR  2008, 73 f). W\u00e4hrend das LG Hamburg (CR 2007, 121 f) es f\u00fcr notwendig  h\u00e4lt, Benutzerkonten einzurichten oder eine Firewall zu installieren,  hat das OLG Frankfurt (a.a.O.) eine \u00dcberwachungspflicht verneint,  solange nicht konkrete Anhaltspunkte f\u00fcr Rechtsverletzungen gerade durch  eines der Familienmitglieder vorliegen. <strong>Welcher dieser Meinungen zu  folgen ist, kann im vorliegenden Verfahren offenbleiben<\/strong>. Den in Anspruch  genommenen Anschlussinhaber trifft n\u00e4mlich eine sekund\u00e4re  Darlegungslast zur Angabe der Person, die nach seiner Kenntnis den  Versto\u00df \u00fcber den betreffenden Anschluss begangen haben kann (vgl. OLG  Frankfurt a.a.O. S. 74). Dem ist die Beklagte im vorliegenden Verfahren  nicht nachgekommen.&#8220;<\/p>\n<p>Etwas sp\u00e4ter f\u00fchrt das OLG am Rande aus, dass der Senat jedenfalls der Meinung ist, dass elterliche \u00dcberwachungspflichten jedenfalls dann einsetzen, wenn die Kinder wissen, dass die Eltern Ihr Verbot auf Grund mangelnder PC-Kenntnisse nicht \u00fcberwachen k\u00f6nnen:<\/p>\n<p style=\"padding-left: 30px;\">&#8222;&#8230;.Damit stellte sich das elterliche Verbot als nicht von Sanktionen  bedroht dar und die Kinder konnten unbeschr\u00e4nkt \u00fcber den PC und den  Internetzugang verf\u00fcgen. <strong>F\u00fcr eine derartige Sanktion ist der Senat nicht der Ansicht, dass  Belehrungs- und Kontrollpflichten der Eltern erst einsetzen, wenn sie  zuvor konkret \u00fcber von ihren Kindern begangenen Rechtsverletzungen  unterrichtet worden sind.&#8220;<\/strong><\/p>\n<p>Der Senat ist also der Meinung, dass Eltern jedenfalls dann, wann sie die Kinder nicht kontrollieren k\u00f6nnen, immer eine besondere \u00dcberwachungspflicht haben. Dies geht nach meiner Ansicht zu weit. \u00dcbertr\u00e4gt man diesen Gedanken auf das &#8222;wirkliche Leben&#8220;, m\u00fcssten alle Kinder, die vielleicht nicht 100% auf Ihre Eltern h\u00f6ren und schneller laufen als diese &#8222;an die Leine genommen werden&#8220;, da die Eltern dann entsprechende Kontrollpflichten haben. Un das nicht erst nach der ersten Rechtsverletzung,\u00a0 sondern sobald die Eltern wissen oder wissen m\u00fcssten, dass diese weglaufen und Unsinnn machen k\u00f6nnten.<\/p>\n<p>Insgesamt hat sich der Senat vor einer klaren Aussage zum Thema &#8222;\u00dcberwachung des Internetanschlusses&#8220; gedr\u00fcckt und insbesondere auch keine konkreten Hinweise gegeben, welche Ma\u00dfnahmen Eltern zu ergreifen haben, um einer m\u00f6glichen St\u00f6rerhaftung f\u00fcr entsprechende urheberrechtsverletzungen der Kinder zu entgehen.<\/p>\n<p>Insbesondere die\u00a0 unbrauchbaren technischen\u00a0 Vorgaben der <a title=\"Urteil des LG K\u00f6ln vom 13.5.2009\" href=\"http:\/\/www.justiz.nrw.de\/nrwe\/lgs\/koeln\/lg_koeln\/j2009\/28_O_889_08urteil20090513.html\" target=\"_blank\">1. Instanz<\/a> spielen den gesch\u00e4ftsm\u00e4\u00dfig agierenden Filesharingabmahnern in die \u00a0 H\u00e4nde, denn wenn keiner Weis wie er sich effektiv vor einer Inanspruchnahme sch\u00fctzen kann, ist das Risiko der Haftung weiterhin unvermeidbar. \u00a0 \u00a0 Zu den M\u00f6glichkeiten der Verhinderung siehe auch <a title=\"Gutachten Prof. Homeister\" href=\"http:\/\/www.oliver-henniges.de\/filesharing\/Gutachten.pdf\" target=\"_blank\">das Gutachten<\/a> von Prof. Homeister aus dem Jahre 2007.<\/p>\n<p>Weiterhin zeigt sich anhand des Urteils des OLG K\u00f6ln aber auch, dass man im Rahmen\u00a0 der Verteidigung die Umst\u00e4nde genau recherchieren und vortragen muss, um nicht in die Gefahr zu geraten wegen fehlenden Vortrags zu den tats\u00e4chlichen Umst\u00e4nden zu verlieren.<br \/>\n<a href=\"http:\/\/www.jurablogs.com\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.jurablogs.com\/widget\/rc\/jurablogs.jpg\" alt=\"JuraBlogs - Die Welt juristischer Blogs\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Besprechung der Entscheidungsgr\u00fcnde des Urteils OLG K\u00f6ln, AZ: 6 U 101\/09 zum Thema Filesharingabmahnung, Kosten und Aufsichtspflichten<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[23,24,31],"tags":[80,125,126,83,127,128,129,130,116,131],"_links":{"self":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/744"}],"collection":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/comments?post=744"}],"version-history":[{"count":0,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/744\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/media?parent=744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/categories?post=744"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/tags?post=744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}