{"id":745,"date":"2010-02-05T17:44:19","date_gmt":"2010-02-05T15:44:19","guid":{"rendered":"http:\/\/mkb-rechtsanwaelte.de\/blog\/wordpress\/?p=131"},"modified":"2010-02-05T17:44:19","modified_gmt":"2010-02-05T15:44:19","slug":"ach-die-schweiz-die-selbstanzeige-in-steuersachen","status":"publish","type":"post","link":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/ach-die-schweiz-die-selbstanzeige-in-steuersachen\/","title":{"rendered":"Ach, die Schweiz &#8230;. die Selbstanzeige in Steuersachen"},"content":{"rendered":"<p><strong> <\/strong><\/p>\n<p>Soll der Staat jene omin\u00f6se CD mit Daten angeblicher Steuerhinterzieher mit Konten in der Schweiz kaufen? Das Ergebnis der Debatte steht fest. Die Bundesrepublik Deutschland wird die CD ankaufen. Die Daten werden ausgewertet und den jeweils zust\u00e4ndigen Finanzbeh\u00f6rden zur Aufdeckung und Verfolgung von Steuerstraftaten \u00fcbergeben werden.<\/p>\n<p><!--more--><\/p>\n<p>Selbstverst\u00e4ndlich k\u00f6nnte es moralisch fragw\u00fcrdig sein, dass ein Rechtsstaat auf ein Angebot eines Datenhehlers eingeht. Allerdings haben die Erfahrungen aus der Lichtenstein-Aff\u00e4re gezeigt, dass derartige Datensammlungen \u00fcber Verm\u00f6gen im Ausland regelm\u00e4\u00dfig zu ganz erheblichen zus\u00e4tzlichen Steuereinnahmen f\u00fchren. Welcher Fiskus k\u00f6nnte aufgrund moralischer Erw\u00e4gungen widerstehen? Immerhin geht es um gesch\u00e4tzte 400 Millionen Euro zus\u00e4tzliche Steuern.<\/p>\n<p>F\u00fcr die m\u00f6glicherweise betroffenen Personen geht es allerdings nicht allein um eine nachzuzahlende Steuer. Es geht vielmehr und in erster Linie um die Frage, ob mit einer Bestrafung gerechnet werden muss. Eine etwaige Geldstrafe (regelm\u00e4\u00dfig in H\u00f6he des hinterzogenen Steuerbetrages) oder gar eine Freiheitsstrafe (regelm\u00e4\u00dfig ohne Bew\u00e4hrung ab einem hinterzogenen Steuerbetrag von 1.000.000 Euro) sind gewichtige Sanktionen.<\/p>\n<p>Das deutsche Recht, genauer: die <a title=\"Die Abgabenordnung \" href=\"http:\/\/gesetze.juris.de\/ao_1977\/index.html\" target=\"_blank\">Abgabenordnung (AO)<\/a>, enth\u00e4lt in <a title=\"Die Selbstanzeige\" href=\"http:\/\/gesetze.juris.de\/ao_1977\/__371.html\" target=\"_blank\">\u00a7 371 AO<\/a> die sogenannte Selbstanzeige. Durch eine ordnungsgem\u00e4\u00dfe Selbstanzeige k\u00f6nnen Steuerpflichtige, die den Finanzbeh\u00f6rden bislang nicht wahrheitsgem\u00e4\u00dfe Angaben \u00fcber ihre Eink\u00fcnfte gemacht haben, den strafrechtlichen Folgen einer bereits begangenen Steuerstraftat entgehen.<\/p>\n<p>Um strafbefreiende Wirkung zu haben muss die Selbstanzeige der zust\u00e4ndigen Finanzbeh\u00f6rde m\u00f6glichst gleich und im ersten Anlauf umfassendes und vollst\u00e4ndiges Material \u00fcber H\u00f6he und Art der bislang nicht erkl\u00e4rten Eink\u00fcnfte sowie den betroffenen Zeitraum liefern.<\/p>\n<p>Dies bedeutet, dass Steuerpflichtige erstens Angaben \u00fcber die Herkunft des im Ausland angelegten Verm\u00f6gens, zweitens \u00fcber die Ertr\u00e4ge des Verm\u00f6gens machen m\u00fcssen: Die Finanzbeh\u00f6rden werden wissen wollen, woher das dort befindliche Geld stammt und ob es m\u00f6glicherweise aus bislang steuerlich nicht erfassten Quellen herr\u00fchrt. Dar\u00fcber hinaus muss mitgeteilt werden, welche Ertr\u00e4ge das im Ausland angelegte Geld in dem fraglichen Zeitraum abgeworfen hat (Zinsen, Dividenden, Ertr\u00e4ge nach dem Investmentsteuergesetz, Ertr\u00e4ge aus privaten Ver\u00e4u\u00dferungsgesch\u00e4ften etc.).<\/p>\n<p>In F\u00e4llen, in denen Steuerpflichtige in Ermangelung von Informationen \u00fcber beispielsweise die Wertentwicklung des Verm\u00f6gens im Ausland keine exakten Angaben machen k\u00f6nnen, kann eine Selbstanzeige auch auf Basis von Sch\u00e4tzungen abgegeben werden. Die Sch\u00e4tzungen sollten ausreichend hoch ausfallen, so dass m\u00f6glichst alle Eink\u00fcnfte, die im Ausland erzielt wurden, von der Sch\u00e4tzung umfasst sind. Nur dann kann die Selbstanzeige auf Basis von Sch\u00e4tzungen zur Straffreiheit f\u00fchren. Selbstverst\u00e4ndlich werden die gesch\u00e4tzten Einnahmen in dem anschlie\u00dfenden Besteuerungsverfahren nicht der Besteuerung zugrunde gelegt. Es geht nur darum, aus der Strafbarkeit herauszukommen. F\u00fcr die Besteuerung k\u00f6nnen die Sch\u00e4tzungen anhand der entsprechenden Dokumente (Ertr\u00e4gnisaufstellungen etc.) dann selbstverst\u00e4ndlich wieder herunter geschraubt werden.<\/p>\n<p>Steuerpflichtigen mit unversteuerten Geldern in der Schweiz, die m\u00f6glicherweise von der aktuellen Daten-Aff\u00e4re betroffen sein k\u00f6nnten, ist deshalb dringend zu raten, die M\u00f6glichkeit zur Selbstanzeige zu nutzen. Hat erst einmal die Steuerfahndung in den fr\u00fchen Morgenstunden an der Haust\u00fcr geklingelt oder wurde die Einleitung des Ermittlungsverfahrens anderweitig mitgeteilt, ist es f\u00fcr eine Selbstanzeige zu sp\u00e4t. Ausschlaggebend ist der Zeitpunkt, in dem Steuerpflichtigen mitgeteilt wird, dass gegen sie ein Ermittlungsverfahren wegen einer Steuerstraftat eingeleitet wurde. Vor dieser Mitteilung kann eine Selbstanzeige noch rechtswirksam abgegeben werden. Danach nicht mehr.<br \/>\n<a href=\"http:\/\/www.jurablogs.com\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.jurablogs.com\/widget\/rc\/jurablogs.jpg\" alt=\"JuraBlogs - Die Welt juristischer Blogs\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Steuerhinterziehung ist das Thema der Woche.\u00dcberall. Auch bei uns. Anbei wird erl\u00e4utert wie man zumindest dem Steuerstrafverfahren entgehen kann, wenn man den Verdacht hat, dass man unbeabsichtigt Teil des Datenhandels der Bundesregierung wurde.  <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[133,141,143],"tags":[132,134,135,136,137,138,139,140,142,144,145,146],"_links":{"self":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/745"}],"collection":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/comments?post=745"}],"version-history":[{"count":0,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/745\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/media?parent=745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/categories?post=745"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/tags?post=745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}