{"id":753,"date":"2016-04-04T19:03:53","date_gmt":"2016-04-04T17:03:53","guid":{"rendered":"http:\/\/mkb-rechtsanwaelte.de\/blog\/wordpress\/?p=742"},"modified":"2016-04-04T19:03:53","modified_gmt":"2016-04-04T17:03:53","slug":"und-schon-wieder-sind-die-banken-einem-bgh-urteil-aus-dem-weg-gegangen","status":"publish","type":"post","link":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/und-schon-wieder-sind-die-banken-einem-bgh-urteil-aus-dem-weg-gegangen\/","title":{"rendered":"Und schon wieder sind die Banken einem BGH-Urteil aus dem Weg gegangen&#8230;.."},"content":{"rendered":"<p style=\"text-align: justify;\">Wie bereits in <a href=\"http:\/\/mkb-rechtsanwaelte.de\/blog\/wordpress\/?p=720\">unserem Blog berichtet<\/a>, scheuen sich die Banken vor einem h\u00f6chstrichterlichen Urteil zum sogenannten &#8222;Widerrufsjoker&#8220; sowie zur Fragestellung der Verwirkung von Widerrufsrechten. Zu dieser Vermeidungsstrategie ist letzte Woche ein <a href=\"http:\/\/www.bundesgerichtshof.de\/SharedDocs\/Termine\/DE\/Termine\/XIZR478.html?nn=6128288\" target=\"_blank\">weiterer Fall hinzugekommen<\/a>.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Das OLG Stuttgart hatte &#8211; gem\u00e4\u00df der wohl \u00fcberwiegenden Meinung der Oberlandsgerichte &#8211; mit <a href=\"http:\/\/lrbw.juris.de\/cgi-bin\/laender_rechtsprechung\/document.py?Gericht=bw&amp;nr=19896\">Urteil vom 29.9.2015 <\/a>entschieden, dass ein Widerruf, der erst nach Abwicklung des Darlehensvertrages erfolgte, wirksam, eine Verwirkung dieses Rechts jedoch nicht gegeben sei.<\/p>\n<p style=\"text-align: justify;\">Auch f\u00fchrt nach Ansicht des OLG Stuttgart eine inhaltliche Bearbeitung dazu, dass\u00a0 der Verwender sich nicht auf die Musterwiderrufsbelehrung des Gesetzgebers berufen kann.\u00a0 Auf Grund der unterschiedlichen Rechtsansichten der verschiedenen Oberlandesgerichte (siehe etwa OLG Frankfurt, Urteil vom 7.7.2014 AZ: 23 U\u00a0 172\/13 &#8211; allerdings noch nicht Rechtskr\u00e4ftig da der BGH f\u00fcr die Nichtzulassungsbeschwerde\u00a0 Prozesskostenhilfe gew\u00e4hrt hat: AZ: <a href=\"https:\/\/openjur.de\/u\/772031.html\">XI Z A 18\/14<\/a>) wurde ausdr\u00fccklich die Revision zugelassen.<\/p>\n<p style=\"text-align: justify;\">Diese wurde auch durch die Bank eingelegt und begr\u00fcndet, da der BGH f\u00fcr den 5. April 2016 einen Termin zur m\u00fcndlichen Verhandlung festgesetzt hatte.<\/p>\n<p style=\"text-align: justify;\">Wie gehabt wurde auch dieser Termin eine Woche vorher\u00a0 durch den BGH aufgehoben, da die Banken als Revisionsf\u00fchrer ihre Revision zur\u00fcckgenommen haben (und somit incident eigentlich dass Urteil des OLG Stuttgart akzeptiert hat. Allerdings entfaltet ein Urteil eines Oberlandsgerichts keine Bindungswirkung f\u00fcr andere Gerichte, wie es beim BGH der Fall w\u00e4re).<\/p>\n<p style=\"text-align: justify;\">Offensichtlich geht es auch hier wieder um Zeitverz\u00f6gerung, um m\u00f6glichst viele Verbraucher von einem Widerruf eines laufenden oder bereits beendeten Darlehensvertrages abzuhalten. Die M\u00f6glichkeiten des Widerrufes eines laufenden oder bereits beendeten\u00a0 Darlehensvertrages wegen eines Fehlers in der Widerrufsbelehrung sind nur noch in einem engen zeitlichen Rahmen m\u00f6glich.<\/p>\n<p style=\"text-align: center;\"><strong>Das bisher unbegrenzte Widerrufsrecht f\u00fcr Altvertr\u00e4ge wird nach aktueller Gesetzeslage\u00a0 zum 21.6.2016 enden. <\/strong><\/p>\n<p style=\"text-align: justify;\">Die Banken m\u00fcssen also nur ein BGH Urteil bis zum 21.6.2016 verhindern (obwohl diese Regelung im Gesetzgebungsverfahren kritisiert wurde siehe<a href=\"https:\/\/www.bundestag.de\/blob\/391616\/94e7d2d327f4d0d48ed9ef6adc2c063a\/knops-data.pdf\" target=\"_blank\"> Gutachten Prof Knops<\/a>). Das bedeutet f\u00fcr die Banken nur noch 10 Wochen &#8222;Verz\u00f6gerungspolitik&#8220;, danach m\u00fcssen Sie nur noch die bis zum 21.6.2016 erfolgten Widerrufe \u201eabarbeiten\u201c. Und solange kein BGH Urteil in der Welt ist, werden erheblich weniger Verbraucher angesichts der Rechtslage ihr Widerrufsrecht aus\u00fcben.<\/p>\n<p style=\"text-align: justify;\">So mutet die gerade heute hier eingegangene\u00a0 Klageerwiderung einer Bank angesichts des obigen Verhaltens geradezu h\u00f6hnisch an, in der\u00a0 nachdr\u00fccklich darauf hingewiesen wird, dass der BGH bisher nicht zur Verwirkung entschieden habe, die Oberlandesgerichte D\u00fcsseldorf und Frankfurt aber eine solche Verwirkung eindeutig annehmen&#8230;..<\/p>\n<p style=\"text-align: justify;\">Wer sich also mit dem Gedanken tr\u00e4gt, den \u201eWiderrufs-Joker\u201c auszu\u00fcben, sollte dies bis sp\u00e4testens\u00a0 Juni 2016 angehen und den Widerruf bis sp\u00e4testens zum 21.6.2016 gegen\u00fcber der finanzierenden Bank ausge\u00fcbt haben.<\/p>\n<p style=\"text-align: justify;\">Angesichts der Strategie der Banken gehe ich davon aus, dass\u00a0 es auch bis zum 21.6.2016 kein Urteil des BGH geben wird. Sollte bis dahin vom BGH noch eine weitere m\u00fcndliche Verhandlung angesetzt werden, wird die Revision dem Verbraucher entweder erneut &#8222;abgekauft&#8220; oder die eigene Revision kurz vor dem Termin zur\u00fcckgenommen werden.<\/p>\n<p style=\"text-align: justify;\">Aus Bankensicht mag dieses auch verst\u00e4ndlich sein, droht doch ein milliardenschwerer Schaden.<\/p>\n<p style=\"text-align: justify;\">Dies wird an dem Beispiel der Vorf\u00e4lligkeitsentsch\u00e4digung deutlich. Die Vorf\u00e4lligkeitsentsch\u00e4digung wird gem\u00e4\u00df \u00a7 502 BGB\u00a0 dann f\u00e4llig, wenn der mit langer Zinsbindungsfrist abgeschlossene\u00a0 Darlehensvertrag (fast alle Immobilienfinanzierungsvertr\u00e4ge sind so ausgestaltet) vorzeitig abgel\u00f6st wird.<\/p>\n<p style=\"text-align: justify;\">Dies passiert h\u00e4ufig, etwa bei einem vorzeitigen Verkauf der Immobilie wegen Scheidung, Erbauseinandersetzung oder sonstigen Gr\u00fcnden. Bei einer Darlehenssumme von 100.000,- \u20ac, geringer Tilgung und hoher Restlaufzeit, sowie Zinsen von 5% j\u00e4hrlich kann da schnell ein Betrag von circa 4.000,- \u20ac pro Jahr (und f\u00fcr jedes weitere Jahr\u00a0 der vorzeitigen Abl\u00f6sung absteigend berechnet) zusammenkommen, bei h\u00f6heren Darlehensbetr\u00e4gen entsprechend mehr. In der Regel bewegen sich Vorf\u00e4lligkeitsentsch\u00e4digungen bei Verbrauchern zwischen 1.000-30.000 \u20ac. F\u00fcr die folgende Beispielrechnung nehmen wir ein Mittel von 15.000,- \u20ac pro Vorf\u00e4lligkeitsentsch\u00e4digung an.<\/p>\n<p style=\"text-align: justify;\">Wenn man jetzt annimmt, dass eine Bank, etwa die \u00f6rtliche Sparkasse,\u00a0 in einem mittelgro\u00dfen Ort pro Jahr 1000 Immobiliendarlehensvertr\u00e4ge abschlie\u00dft und nur 5% der Immobiliendarlehensvertr\u00e4ge pro Jahr\u00a0 vorzeitig beendet werden, ist man bei\u00a0 j\u00e4hrlichen Vorf\u00e4lligkeitsentsch\u00e4digungen in H\u00f6he von 50 x 15.000= 750.000,- \u20ac. Auf den Zeitraum 2003 bis Ende 2010 (zu diesem Zeitpunkt wurden die meisten der falschen Widerrufsbelehrungen ge\u00e4ndert) berechnet bedeutet dies einen Umsatz f\u00fcr die kleine mittelst\u00e4ndische Sparkasse von circa 6.000.000,- \u20ac. Dabei\u00a0 ist das\u00a0 nur die kleine Sparkasse nebenan, hochgerechnet auf alle Banken sind die Ums\u00e4tze mit Vorf\u00e4lligkeitsentsch\u00e4digungen\u00a0 in diesen 8 Jahren\u00a0 bestimmt im zweistelligen Milliardenbereich. Entscheidet nun der BGH noch vor dem 21.6.2016 zu Gunsten der Verbraucher, und nehmen nur 10% der damaligen Darlehensnehmer\u00a0 ihr Widerrufsrecht noch nachtr\u00e4glich war, bedeutet dies immer noch einen Milliardenverlust f\u00fcr die Banken.<\/p>\n<p style=\"text-align: justify;\">Schaffen es die Banken\u00a0 jedoch, ein solches h\u00f6chstrichterliches Urteil bis nach den 21.6.2016 hinaus zu z\u00f6gern, ist der Verbraucher auf Grund der Gesetzeslage von dem urspr\u00fcnglichen Widerrufsrecht &#8222;abgeschnitten&#8220;. Die Banken m\u00fcssen dann nur noch die &#8222;Altf\u00e4lle&#8220; also die bis zum 21.6.2016 eingegangenen Widerrufe bearbeiten.<\/p>\n<p style=\"text-align: justify;\">Auf Grund der unsicheren Rechtslage, den bei derartigen Streitwerten\u00a0 erh\u00f6hten Prozesskostenrisiko (das bei einem Streitwert von 15.000,- \u20ac und 2 Instanzen immerhin 10.345,30 \u20ac betr\u00e4gt) und der meist fehlenden Deckung der Rechtsschutzversicherung (die sich immer auf den Ausschlu\u00dftatbestand &#8222;Finanzierung von Immobilien&#8220; berufen wird) wird bis zum 21.6.2016 lediglich ein verschwindend\u00a0 geringer Teil der ehemaligen Darlehensnehmer \u00fcber einen Widerruf nachdenken.<\/p>\n<p style=\"text-align: justify;\">Allerdings besteht besonders\u00a0 f\u00fcr ehemalige Darlehensnehmer die M\u00f6glichkeit , sich alle Optionen offen zu halten. Hierf\u00fcr sollte die damalige Widerrufsbelehrung des Darlehensvertrages von einem Fachmann (Verbraucherzentrale, Rechtsanw\u00e4lte) \u00fcberpr\u00fcft werden. Ist die Widerrufsbelehrung falsch, sollte in jedem Fall der Widerruf gegen\u00fcber der Bank noch ausge\u00fcbt werden. Entscheidet der BGH \u00a0 nach dem 21.6.2016 zu Gunsten der Verbraucher, k\u00f6nnen diejenigen, die vorher ihr Widerspruchsrecht ausge\u00fcbt haben, ihre Rechte auf R\u00fcckzahlung der Vorf\u00e4lligkeitsentsch\u00e4digung noch geltend machen. Die F\u00e4lle aus dem Bereich der Bearbeitungsgeb\u00fchren zeigen, dass eine Verj\u00e4hrung dieser Anspr\u00fcche erst mit den ersten obergerichtlichen Entscheidungen zum Widerrufsjoker beginnt (siehe zur Verj\u00e4hrung von R\u00fcckforderungsanspr\u00fcchen von Bearbeitungsentgeld <a href=\"https:\/\/openjur.de\/u\/744406.html\" target=\"_blank\">BGH Urteil vom 28.10.2014 AZ: XI ZR 17\/14<\/a>).<\/p>\n<p style=\"text-align: justify;\">Ein vorsorglich erhobener Widerspruch bis zum 21.6.2016 kostet daher nur eine Beratungsgeb\u00fchr bei der Verbraucherzentrale oder dem\u00a0 Rechtsanwalt.<\/p>\n<p style=\"text-align: justify;\">_____________________________________________________________________________<\/p>\n<p style=\"text-align: justify;\">Die Kanzlei Mielke Koy Butenberg ber\u00e4t\u00a0 Sie auch in allen Fragen des Bankenrechts.<\/p>\n<p style=\"text-align: justify;\">G\u00fcnther Koy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie bereits in unserem Blog berichtet, scheuen sich die Banken vor einem h\u00f6chstrichterlichen Urteil zum sogenannten &#8222;Widerrufsjoker&#8220; sowie zur Fragestellung der Verwirkung von Widerrufsrechten. Zu dieser Vermeidungsstrategie ist letzte Woche ein weiterer Fall hinzugekommen. Das OLG Stuttgart hatte &#8211; gem\u00e4\u00df<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[594,596,667],"tags":[664,154,659,674,428],"_links":{"self":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/753"}],"collection":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/comments?post=753"}],"version-history":[{"count":0,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/posts\/753\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/media?parent=753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/categories?post=753"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mk-rechtsanwaelte.de\/mk\/wp-json\/wp\/v2\/tags?post=753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}